{"id":45,"count":1,"description":"","link":"https:\/\/thobi-licenses.net\/en\/tag\/best-in-town-your-hotline\/","name":"Best in Town! Your Hotline","slug":"best-in-town-your-hotline","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/thobi-licenses.net\/en\/wp-json\/wp\/v2\/tags\/45","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thobi-licenses.net\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/thobi-licenses.net\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/thobi-licenses.net\/en\/wp-json\/wp\/v2\/posts?tags=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}