{"id":26,"count":1,"description":"","link":"https:\/\/thobi-licenses.net\/en\/tag\/das-kalte-herz\/","name":"Das Kalte Herz","slug":"das-kalte-herz","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/thobi-licenses.net\/en\/wp-json\/wp\/v2\/tags\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thobi-licenses.net\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/thobi-licenses.net\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/thobi-licenses.net\/en\/wp-json\/wp\/v2\/posts?tags=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}